{"id":1192,"name":"Diego Sztulwark","url":"","description":"Diego Sztulwark: Investigador y escritor. Estudi\u00f3 Ciencia Pol\u00edtica en la Universidad de Buenos Aires. Es docente y coordina grupos de estudio sobre filosof\u00eda y pol\u00edtica,  es uno de los l\u00edderes del grupo \"El Mate\", que re\u00fane a defensores de los derechos humanos y activistas radicales de la sociedad civil en Argentina.\r\n\r\n\r\n\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\r\n\r\nDiego Sztulwark : Chercheur et \u00e9crivain. Il a \u00e9tudi\u00e9 les sciences politiques \u00e0 l'universit\u00e9 de Buenos Aires. Il enseigne et coordonne des groupes d'\u00e9tude sur la philosophie et la politique, et est l'un des dirigeants du groupe \"El Mate\", qui rassemble des d\u00e9fenseurs des droits de l'homme et des militants radicaux de la soci\u00e9t\u00e9 civile en Argentine.","link":"https:\/\/www.lapluma.net\/fr\/author\/diego-sztulwark\/","slug":"diego-sztulwark","meta":{"rsssl_two_fa_status":"disabled"},"_links":{"self":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/users\/1192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/users"}]}}