{"id":5785,"date":"2019-01-28T16:28:24","date_gmt":"2019-01-28T16:28:24","guid":{"rendered":"http:\/\/www.lapluma.net\/?p=5785"},"modified":"2019-02-09T01:53:44","modified_gmt":"2019-02-09T01:53:44","slug":"propaganda-contra-venezuelabr-la-escuela-del-mundo-al-reves","status":"publish","type":"post","link":"https:\/\/www.lapluma.net\/fr\/2019\/01\/28\/propaganda-contra-venezuelabr-la-escuela-del-mundo-al-reves\/","title":{"rendered":"Propagande contre le Venezuela <br><i>L&rsquo;\u00e9cole du monde \u00e0 l&rsquo;envers<\/i>"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><b><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/www.tlaxcala-int.org\/upload\/aut_2958.jpg\" width=\"98\" height=\"93\" border=\"0\" \/><\/strong>La mayonnaise Guaido ne prend pas La mayonnaise Guaido ne prend pas La mayonnaise Guaido ne prend pas Le pr\u00e9sident fran\u00e7ais<\/b>, Emmanuel Macron, ordonne \u00e1 Nicolas Maduro de ne pas r\u00e9primer l\u2019opposition\u00a0<b>MAIS IL OUBLIE\u00a0<\/b>les 3 300 arrestations et les 2 000 bless\u00e9s li\u00e9s \u00e0 la r\u00e9pression du mouvement des gilets jaunes.\u00a0<\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><b>Le pr\u00e9sident du gouvernement espagnol<\/b>, Pedro Sanchez, donne huit jours \u00e0 Nicolas Maduro pour organiser des \u00e9lections\u00a0<b>MAIS IL OUBLIE\u00a0<\/b>qu\u2019il n\u2019est \u00e0 son poste que gr\u00e2ce \u00e0 une motion de censure, et non par des \u00e9lections libres.<\/span><\/div>\n<div><\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.tlaxcala-int.org\/upload\/gal_19663.jpg\" alt=\"\" width=\"500\" height=\"625\" \/><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Le pr\u00e9sident des \u00c9tats-Unis, Donald Trump, accuse Nicolas Maduro de ne pas \u00eatre l\u00e9gitime car le pr\u00e9sident v\u00e9n\u00e9zu\u00e9lien n\u2019a \u00e9t\u00e9 \u00e9lu qu\u2019avec 30,45% des inscrits,\u00a0MAIS IL OUBLIE\u00a0que seulement 27,20% des \u00e9lecteurs \u00e9tatsuniens l\u2019ont choisi.<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Le pr\u00e9sident colombien, Ivan Duque crie \u00e0 la\u00a0\u201cnarco-dictature v\u00e9n\u00e9zu\u00e9lienne\u201d\u00a0MAIS IL OUBLIE\u00a0que 65% de la coca\u00efne dans le monde est fabriqu\u00e9e en Colombie, sous le regard complaisant des autorit\u00e9s du pays.\u00a0<\/span><br \/>\n<span style=\"font-size: 12pt;\"><br \/>\nLe pr\u00e9sident br\u00e9silien,\u00a0Jair Bolsonaro,\u00a0est pr\u00e9occup\u00e9 par les droits de l\u2019homme au Venezuela\u00a0MAIS IL OUBLIE\u00a0qu\u2019il a d\u00e9clar\u00e9\u00a0que les mouvements sociaux qui s\u2019opposeraient \u00e0 sa politique seraient consid\u00e9r\u00e9s comme organisations terroristes.<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Le pr\u00e9sident argentin, Mauricio Macri, accuse Nicolas Maduro d\u2019\u00eatre un corrompu\u00a0MAIS IL OUBLIE\u00a0que seul son nom apparait dans les\u00a0<i>Panama Papers<\/i>, pas celui du pr\u00e9sident v\u00e9n\u00e9zu\u00e9lien.\u00a0<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Le Portugal\u00a0d\u00e9plore la crise v\u00e9n\u00e9zu\u00e9lienne qui, selon l\u2019ONU, a pouss\u00e9 7,2% des V\u00e9n\u00e9zu\u00e9liens sur les chemins de l\u2019\u00e9migration\u00a0MAIS IL OUBLIE\u00a0que 21% des Portugais ont d\u00fb abandonner leur pays et vivent \u00e0 l\u2019\u00e9tranger, selon les m\u00eames sources.\u00a0<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Le pr\u00e9sident p\u00e9ruvien, Martin Vizcarra, crie \u00e0 la dictature au Venezuela\u00a0MAIS IL OUBLIE\u00a0qu\u2019il a \u00e9t\u00e9 nomm\u00e9 \u00e0 la t\u00eate de son pays sans le moindre vote populaire, juste en remplacement du pr\u00e9c\u00e9dent pr\u00e9sident, destitu\u00e9 pour corruption.\u00a0<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Au Royaume-Uni, les dirigeants d\u00e9noncent les atteintes \u00e0 la libert\u00e9 d\u2019expression au Venezuela\u00a0MAIS ILS OUBLIENT\u00a0qu\u2019ils maintiennent, sans aucun motif valable, le journaliste Julian Assange en r\u00e9clusion forc\u00e9e.\u00a0<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">La Belgique\u00a0s\u2019alarme de la situation de l\u2019\u00e9conomie v\u00e9n\u00e9zu\u00e9lienne MAIS\u00a0ELLE OUBLIE\u00a0qu\u2019\u00e0 Bruxelles, l\u2019entreprise\u00a0<i>Euroclear\u00a0<\/i>retient 1,25 milliards de dollars appartenant \u00e0 l\u2019Etat v\u00e9n\u00e9zu\u00e9lien.<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Ces inversions accusatoires, propres \u00e0 cette \u201c\u00e9cole du monde \u00e0 l\u2019envers\u201d d\u00e9crite par Eduardo Galeano,\u00a0\u00a0font partie du\u00a0<i>modus operandi\u00a0<\/i>de la propagande contre le Venezuela. Elles visent \u00e0 pr\u00e9parer l\u2019opinion publique internationale \u00e0 la l\u00e9gitimit\u00e9 d\u2019une action violente contre le peuple v\u00e9n\u00e9zu\u00e9lien.\u00a0<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Les bombes m\u00e9diatiques sont d\u00e9j\u00e0 en train de pleuvoir.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>Romain Migus pour La Pluma, le 28 janvier 2019<\/strong><\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Traductions disponibles: <a href=\"http:\/\/www.lapluma.net\/2019\/01\/28\/propaganda-contra-venezuelabr-la-escuela-del-mundo-al-reves\/\">Espa\u00f1ol<\/a>\u00a0\u00a0\u00a0\u00a0 <a href=\"http:\/\/www.tlaxcala-int.org\/article.asp?reference=25192\">Italiano<\/a><\/strong><\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Source: <a href=\"https:\/\/www.romainmigus.info\/2019\/01\/propagande-contre-le-venezuela.html\">Venezuela en Vivo<\/a><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ces inversions accusatoires, propres \u00e0 cette \u201c\u00e9cole du monde \u00e0 l\u2019envers\u201d d\u00e9crite par Eduardo Galeano,  font partie du modus operandi de la propagande contre le Venezuela. Elles visent \u00e0 pr\u00e9parer l\u2019opinion publique internationale \u00e0 la l\u00e9gitimit\u00e9 d\u2019une action violente contre le peuple v\u00e9n\u00e9zu\u00e9lien. <\/p>\n","protected":false},"author":159,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[218],"tags":[],"coauthors":[1376],"class_list":["post-5785","post","type-post","status-publish","format-standard","hentry","category-monde"],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"fr","enabled_languages":["es","fr"],"languages":{"es":{"title":true,"content":true,"excerpt":true},"fr":{"title":true,"content":true,"excerpt":true}}},"_links":{"self":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/posts\/5785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/comments?post=5785"}],"version-history":[{"count":7,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/posts\/5785\/revisions"}],"predecessor-version":[{"id":5789,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/posts\/5785\/revisions\/5789"}],"wp:attachment":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/media?parent=5785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/categories?post=5785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/tags?post=5785"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/coauthors?post=5785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}