{"id":54987,"date":"2023-07-26T19:18:35","date_gmt":"2023-07-26T19:18:35","guid":{"rendered":"https:\/\/www.lapluma.net\/?p=54987"},"modified":"2023-07-26T21:23:10","modified_gmt":"2023-07-26T21:23:10","slug":"china-una-mirada-desde-shanghai","status":"publish","type":"post","link":"https:\/\/www.lapluma.net\/fr\/2023\/07\/26\/china-una-mirada-desde-shanghai\/","title":{"rendered":"China: una mirada desde Shangh\u00e1i"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Escribo desde Shangh\u00e1i a donde llegu\u00e9 el domingo pasado. El calor en las calles de esta urbe de 24.7 millones de habitantes es abrumador. Shangh\u00e1i se encuentra en la regi\u00f3n oriental de China, es una ciudad fluvial ubicada a 20 Km. del mar en el delta del r\u00edo Yangtz\u00e9 el m\u00e1s importante de China y uno de los m\u00e1s largos del mundo.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-54993\" src=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/yangtze_river_map-300x179.jpg\" alt=\"\" width=\"600\" height=\"358\" srcset=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/yangtze_river_map-300x179.jpg 300w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/yangtze_river_map.jpg 580w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Tambi\u00e9n es la metr\u00f3poli m\u00e1s poblada del pa\u00eds a pesar de que el a\u00f1o pasado redujo su poblaci\u00f3n por primera vez en la historia. La esperanza de vida de sus habitantes es de 83.2 a\u00f1os, similar por ejemplo a la de Noruega y Suecia. Es junto a Beijing, Tianjin y Chongqing, uno de los cuatro municipios administrados centralmente por el gobierno nacional del pa\u00eds.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Desde el punto de vista de su geograf\u00eda, la ciudad est\u00e1 cruzada por el r\u00edo Huangpu, afluente del Yangtz\u00e9 que la divide en dos sectores: el occidental donde se encuentra el centro hist\u00f3rico y el oriental donde est\u00e1 el distrito financiero de Pudong. Tiene alrededor de 4000 rascacielos, algunos de ellos, los m\u00e1s altos del mundo. Su red de centros culturales, deportivos y de diversi\u00f3n es impresionante.<\/span><\/p>\n<figure id=\"attachment_55000\" aria-describedby=\"caption-attachment-55000\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-55000\" src=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/shanghai-Centro-Historico-300x222.jpg\" alt=\"\" width=\"550\" height=\"406\" srcset=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/shanghai-Centro-Historico-300x222.jpg 300w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/shanghai-Centro-Historico-768x567.jpg 768w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/shanghai-Centro-Historico.jpg 960w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><figcaption id=\"caption-attachment-55000\" class=\"wp-caption-text\">hanghai, Centre historique, Route renmin.<\/figcaption><\/figure>\n<figure id=\"attachment_55001\" aria-describedby=\"caption-attachment-55001\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-55001\" src=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/Shangai-Centro-financiero-300x201.jpg\" alt=\"\" width=\"550\" height=\"368\" srcset=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/Shangai-Centro-financiero-300x201.jpg 300w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/Shangai-Centro-financiero-435x290.jpg 435w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/Shangai-Centro-financiero-150x100.jpg 150w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/Shangai-Centro-financiero-370x247.jpg 370w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/Shangai-Centro-financiero.jpg 600w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><figcaption id=\"caption-attachment-55001\" class=\"wp-caption-text\">Centro financiero de Shanghai<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El tema econ\u00f3mico cubre la agenda informativa del pa\u00eds. No hablo ni entiendo chino-mandar\u00edn, pero me informo a la vieja usanza por los peri\u00f3dicos en ingl\u00e9s que se siguen editando con profusi\u00f3n en papel como les gusta a las personas de mi generaci\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Recientemente, la semana pasada se realiz\u00f3 un importante simposio con personalidades que no son militantes del partido comunista de China en la que particip\u00f3 el presidente Xi Jinping. Se trataba de consultar y debatir acerca de la situaci\u00f3n econ\u00f3mica del pa\u00eds y las tareas a enfrentar en el segundo semestre del a\u00f1o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Seg\u00fan el presidente chino hay que buscar el progreso manteniendo la estabilidad. Para ello, es necesario aplicar una original filosof\u00eda del desarrollo construyendo un nuevo patr\u00f3n que profundice la pol\u00edtica de reforma y apertura, expandiendo la demanda interna, aumentando la confianza y previniendo los riesgos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El desempe\u00f1o econ\u00f3mico de China en el primer semestre del a\u00f1o mostr\u00f3 signos de recuperaci\u00f3n. El PIB creci\u00f3 5,5% interanual mostrando una aceleraci\u00f3n notable respecto del a\u00f1o pasado. Creci\u00f3 la oferta agr\u00edcola, la industria y el consumo sobre todo el de alta calidad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Hay grandes expectativas en el pa\u00eds e incluso en organismos financieros internacionales como el Banco Mundial y el Fondo Monetario Internacional de que el crecimiento econ\u00f3mico de China sea positivo para si misma y para el mundo al contrario de lo que ocurre en la mayor parte del planeta. En lo interno, el crecimiento har\u00e1 una gran contribuci\u00f3n a la demanda interna del PIB mostrando una tendencia creciente al alza.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-54994 aligncenter\" src=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/cotw-growth-contributions-chart-spa-300x300.png\" alt=\"\" width=\"517\" height=\"517\" srcset=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/cotw-growth-contributions-chart-spa-300x300.png 300w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/cotw-growth-contributions-chart-spa-1024x1024.png 1024w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/cotw-growth-contributions-chart-spa-150x150.png 150w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/cotw-growth-contributions-chart-spa-768x768.png 768w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/cotw-growth-contributions-chart-spa.png 1100w\" sizes=\"auto, (max-width: 517px) 100vw, 517px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Aument\u00f3 la producci\u00f3n de celdas solares, veh\u00edculos el\u00e9ctricos y pilas de carga. Esto es notable a la simple vista de cualquiera y supone -para mi- el cambio m\u00e1s ostensible de la ciudad desde mi \u00faltimo viaje hace cuatro a\u00f1os. Se puede percibir por el incremento en calles y avenidas de las pilas de carga para veh\u00edculos el\u00e9ctricos y las placas verdes de estos, a diferencia de las tradicionales de color azul.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Aunque Shangh\u00e1i es una ciudad de alto nivel de desarrollo, las personas con quienes he conversado (colegas y amigos) destacan las evidentes repercusiones en el consumo que se observa tras la victoria obtenida por el pa\u00eds en la lucha contra la pobreza extrema en el a\u00f1o 2020, acentuando la posibilidad de que este flagelo sea definitivamente extirpado de la realidad nacional en 2049 tal como se lo han propuesto las autoridades.<\/span><\/p>\n<figure id=\"attachment_54995\" aria-describedby=\"caption-attachment-54995\" style=\"width: 581px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-54995\" src=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/Shangai-al-borde-del-mar--300x82.jpg\" alt=\"\" width=\"581\" height=\"159\" srcset=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/Shangai-al-borde-del-mar--300x82.jpg 300w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/Shangai-al-borde-del-mar--768x210.jpg 768w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/07\/Shangai-al-borde-del-mar-.jpg 800w\" sizes=\"auto, (max-width: 581px) 100vw, 581px\" \/><figcaption id=\"caption-attachment-54995\" class=\"wp-caption-text\"><a href=\"https:\/\/chine.in\/guide\/shanghai_780.html\">Panorama Shanghai<\/a><br \/>Shangh\u00e1i o Shang-Hai \u4e0a\u6d77 (\u00ab\u00a0sobre el mar\u00a0\u00bb) es la mayor ciudad de China, con 2.588 habitantes por kil\u00f3metro cuadrado.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">As\u00ed mismo, se distingue una clara recuperaci\u00f3n del turismo tras la pandemia: la alta afluencia de personas en restaurantes, aeropuertos y terminales ferroviarias dan cuenta de ello. Algunos amigos con los que he conversado me dicen que se ha hecho muy dif\u00edcil conseguir boletos de trenes y aviones.<\/span><br \/>\n<span style=\"font-size: 14pt;\">Claro, estamos en pleno verano, temporada vacacional de ni\u00f1os y j\u00f3venes que junto a sus padres aprovechan para salir de la ciudad. De igual manera, se ven aglomeraciones juveniles en actividades deportivas, culturales y recreativas en los m\u00faltiples espacios que la ciudad ha creado para el esparcimiento. En perspectiva, la vecina ciudad de Hangzhou se prepara con toda pompa para la celebraci\u00f3n -sin atletas sancionados- de los XIX juegos asi\u00e1ticos entre el 23 de septiembre y el 8 octubre de este a\u00f1o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Pero no todo es \u201cmiel sobre hojuelas\u201d. El pa\u00eds tambi\u00e9n enfrenta dificultades propias de una sociedad que resuelve algunos problemas para que surjan otros. El impacto de la pandemia todav\u00eda no se ha subsanado del todo. A pesar de los \u00edndices econ\u00f3micos positivos, en un pa\u00eds que en el pasado creci\u00f3 al 8% y m\u00e1s anualmente, algunos sectores de la poblaci\u00f3n no perciben a\u00fan la normalizaci\u00f3n de la situaci\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Mucho j\u00f3venes -sobre todo reci\u00e9n graduados de las universidades- tienen severas dificultades para conseguir empleo. Al mismo tiempo, algunos colegas me se\u00f1alaron que observan con preocupaci\u00f3n que en el pa\u00eds se manifiesten los mismos cambios generacionales que afectan al planeta: j\u00f3venes que s\u00f3lo desean una vida tranquila, no quieren casarse ni tener hijos, Tampoco desean asumir responsabilidades.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El a\u00f1o pasado l<a href=\"https:\/\/www.swissinfo.ch\/spa\/afp\/la-poblaci%C3%B3n-china-disminuye-por-primera-vez-en-m%C3%A1s-de-60-a%C3%B1os\/48209502\">a poblaci\u00f3n de China disminuy\u00f3 por primera vez desde principios de la d\u00e9cada de los a\u00f1os 60 del siglo pasado.<\/a> Esto, junto al envejecimiento de la poblaci\u00f3n plantea riesgos virtuales para la econom\u00eda del pa\u00eds a futuro. Como se puede percibir, China comienza a mostrar los males de las sociedades desarrolladas del \u201cprimer mundo\u201d: la pir\u00e1mide demogr\u00e1fica invertida en materia laboral es uno de ellos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Acostumbrados a recibir informaci\u00f3n de China en su calidad de actor internacional, quise en esta ocasi\u00f3n, dar a conocer estas cortas reflexiones para intentar mostrar algunos aspectos que he percibido en estos pocos d\u00edas desde mi llegada de la faceta interna de esta siempre interesante naci\u00f3n que vive en constante y acelerado movimiento.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-size: 18pt;\">Sergio Rodr\u00edguez gelfenstein para La Pluma, 26 de julio de 2023<br \/>\n<\/span><\/h2>\n<h2 style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><span style=\"font-size: 18pt;\">Editado por <\/span><a href=\"http:\/\/www.lapluma.net\/nosotros\/editora\/\"><span style=\"font-size: 18pt;\">Mar\u00eda Piedad Ossaba<\/span><\/a><\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Acostumbrados a recibir informaci\u00f3n de China en su calidad de actor internacional, quise en esta ocasi\u00f3n, dar a conocer estas cortas reflexiones para intentar mostrar algunos aspectos que he percibido en estos pocos d\u00edas desde mi llegada de la faceta interna de esta siempre interesante naci\u00f3n que vive en constante y acelerado movimiento.<\/p>\n","protected":false},"author":9,"featured_media":54997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[5],"tags":[14660,23902,23901],"coauthors":[266],"class_list":["post-54987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editoriales-y-opiniones","tag-china","tag-desarrollo-en-shangai","tag-shangai"],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"fr","enabled_languages":["es","fr"],"languages":{"es":{"title":true,"content":true,"excerpt":true},"fr":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/posts\/54987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/comments?post=54987"}],"version-history":[{"count":6,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/posts\/54987\/revisions"}],"predecessor-version":[{"id":54999,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/posts\/54987\/revisions\/54999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/media\/54997"}],"wp:attachment":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/media?parent=54987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/categories?post=54987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/tags?post=54987"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/coauthors?post=54987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}