{"id":48808,"date":"2023-02-13T13:52:54","date_gmt":"2023-02-13T13:52:54","guid":{"rendered":"https:\/\/www.lapluma.net\/?p=48808"},"modified":"2023-02-13T20:25:18","modified_gmt":"2023-02-13T20:25:18","slug":"crisis-mundial-a-tres-bandas-energia-alimentos-clima-y-las-guerras","status":"publish","type":"post","link":"https:\/\/www.lapluma.net\/fr\/2023\/02\/13\/crisis-mundial-a-tres-bandas-energia-alimentos-clima-y-las-guerras\/","title":{"rendered":"Crisis mundial a tres bandas: Energ\u00eda, alimentos, clima. Y las guerras"},"content":{"rendered":"<h2 style=\"text-align: justify;\"><strong><em><span style=\"font-size: 18pt; color: #ff0000;\">Nada de nuevo en Davos. \u00bfQu\u00e9 preparan para octubre el FMI y el BM?<\/span><\/em><\/strong><\/h2>\n<div class=\"ydpdc81c5dayiv4181523493ydpdaed15a6pasted-link\">\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><i>La cooperaci\u00f3n en un mundo fragmentado<\/i> &#8211;lema del Foro realizado la segunda quincena de enero&#8211;qued\u00f3 s\u00f3lo como un slogan publicitario ya que el mismo prefiere no confrontarse con las causas profundas de la crisis porque no parece dispuesto a rectificar este laberinto planetario sin salida, en este contexto actual, para el conjunto de la humanidad. <\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El reloj del poder econ\u00f3mico internacional marca ahora una nueva cita: del 9 al 15 de octubre de este a\u00f1o en Marrakech, Marruecos, donde muchos de los que asistieron a Davos volver\u00e1n a encontrarse en la Reuni\u00f3n Anual del Banco Mundial y del Fondo Monetario Internacional. Las se\u00f1ales de la invitaci\u00f3n para Marrakech de parte de estos dos organismos multilaterales anticipan continuismo y ning\u00fan cambio. <\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Las primeras voces alternativas comienzan a alzar el tono. El Comit\u00e9 para la Anulaci\u00f3n de las Deudas Ileg\u00edtimas (CADTM) anticip\u00f3 en las \u00faltimas horas que convocar\u00e1 con otras organizaciones, como ATTAC Marruecos, a una <a href=\"https:\/\/www.cadtm.org\/Convocatoria-de-una-contracumbre-mundial-de-movimientos-sociales-a-las\">Contracumbre Mundial de los Movimientos Sociales<\/a>\u00a0 para esa misma fecha.<\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-48815 aligncenter\" src=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/CADTM-Contracumbe-Mundial-300x300.png\" alt=\"\" width=\"438\" height=\"438\" srcset=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/CADTM-Contracumbe-Mundial-300x300.png 300w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/CADTM-Contracumbe-Mundial-150x150.png 150w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/CADTM-Contracumbe-Mundial.png 640w\" sizes=\"auto, (max-width: 438px) 100vw, 438px\" \/><\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El CADTM se\u00f1ala que el Fondo Monetario Internacional (FMI) firm\u00f3 en los \u00faltimos tres a\u00f1os acuerdos de cr\u00e9dito con un centenar de gobiernos, y que en cada uno de los mismos exige la continuaci\u00f3n de las pol\u00edticas neoliberales. Al mismo tiempo, denuncia que se est\u00e1 desarrollando una nueva crisis de la\u00a0deuda. \u201cYa es hora de reaccionar\u201d, sostiene el comit\u00e9 con sede en Bruselas, tras definir la situaci\u00f3n actual como de una \u201ccrisis multifac\u00e9tica\u201d que afecta al mundo desde 2020.<\/span><\/p>\n<h5 class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 18pt;\"><b>Policrisis<\/b><\/span><\/h5>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Una tomograf\u00eda computarizada de la actual realidad mundial muestra que un tercio de la demanda total de energ\u00eda est\u00e1 ligada a la producci\u00f3n de alimentos. Por lo tanto, todo aumento en el precio de la energ\u00eda incide directamente en el precio de los comestibles. Esta relaci\u00f3n es particularmente obvia cuando se trata de combustibles f\u00f3siles &#8211;petr\u00f3leo, carb\u00f3n, gas natural&#8211;, utilizados en grandes cantidades en los cultivos, el procesado de alimentos, el empaque, el transporte y la venta minorista.<\/span><\/p>\n<figure id=\"attachment_48810\" aria-describedby=\"caption-attachment-48810\" style=\"width: 518px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48810\" src=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Crisis-climatica-junto-con-la-crisis-energetica-y-la-repercusion-en-los-precios-de-los-alimentos_-Fermula-explosiva-de-la-POLICRISIS-mundia_-Foto-PAM-300x200.jpg\" alt=\"\" width=\"518\" height=\"346\" srcset=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Crisis-climatica-junto-con-la-crisis-energetica-y-la-repercusion-en-los-precios-de-los-alimentos_-Fermula-explosiva-de-la-POLICRISIS-mundia_-Foto-PAM-300x200.jpg 300w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Crisis-climatica-junto-con-la-crisis-energetica-y-la-repercusion-en-los-precios-de-los-alimentos_-Fermula-explosiva-de-la-POLICRISIS-mundia_-Foto-PAM-768x512.jpg 768w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Crisis-climatica-junto-con-la-crisis-energetica-y-la-repercusion-en-los-precios-de-los-alimentos_-Fermula-explosiva-de-la-POLICRISIS-mundia_-Foto-PAM-435x290.jpg 435w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Crisis-climatica-junto-con-la-crisis-energetica-y-la-repercusion-en-los-precios-de-los-alimentos_-Fermula-explosiva-de-la-POLICRISIS-mundia_-Foto-PAM-150x100.jpg 150w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Crisis-climatica-junto-con-la-crisis-energetica-y-la-repercusion-en-los-precios-de-los-alimentos_-Fermula-explosiva-de-la-POLICRISIS-mundia_-Foto-PAM-370x247.jpg 370w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Crisis-climatica-junto-con-la-crisis-energetica-y-la-repercusion-en-los-precios-de-los-alimentos_-Fermula-explosiva-de-la-POLICRISIS-mundia_-Foto-PAM.jpg 1024w\" sizes=\"auto, (max-width: 518px) 100vw, 518px\" \/><figcaption id=\"caption-attachment-48810\" class=\"wp-caption-text\">Crisis clim\u00e1tica junto con la crisis energ\u00e9tica y la repercusi\u00f3n en los precios de los alimentos_ F\u00e9rmula explosiva de la POLICRISIS mundia. Foto PAM<\/figcaption><\/figure>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Este diagn\u00f3stico forma parte de las conclusiones a las que llega la organizaci\u00f3n no gubernamental internacional <i><a href=\"https:\/\/grain.org\/es\/article\/6912-una-salida-a-la-crisis-alimentaria-energetica-climatica\">Grain<\/a> (Grano, <\/i>en espa\u00f1ol), que desde hace 33 a\u00f1os viene trabajando al servicio de los movimientos sociales rurales en sus luchas por sistemas alimentarios basados en la biodiversidad y controlados comunitariamente.<br \/>\n<\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Seg\u00fan una publicaci\u00f3n de <i>Grain<\/i> de noviembre del a\u00f1o pasado, la relaci\u00f3n entre alimentos y energ\u00eda tiene una mayor incidencia en la producci\u00f3n altamente mecanizada, predominante en Europa, Norte Am\u00e9rica y algunas regiones de Am\u00e9rica Latina. En estas regiones, la cantidad de energ\u00eda que se necesita para producir, por ejemplo, una tonelada de cereal, es casi 2,5 veces mayor que en los minifundios de los pa\u00edses del Sur. \u00a0En t\u00e9rminos reales, el sistema alimentario industrializado de Estados Unidos consume la energ\u00eda equivalente al gasto energ\u00e9tico total de India o de todas las naciones africanas juntas.<\/span><\/p>\n<figure id=\"attachment_48820\" aria-describedby=\"caption-attachment-48820\" style=\"width: 633px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48820\" src=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Los-cultivos-locales-se-presentan-como-alternativas-a-las-transnacionales-de-alimentos-_-Cultivo-de-quinoa-en-una-region-andina-Foto-FAO-3-300x136.jpg\" alt=\"\" width=\"633\" height=\"287\" srcset=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Los-cultivos-locales-se-presentan-como-alternativas-a-las-transnacionales-de-alimentos-_-Cultivo-de-quinoa-en-una-region-andina-Foto-FAO-3-300x136.jpg 300w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Los-cultivos-locales-se-presentan-como-alternativas-a-las-transnacionales-de-alimentos-_-Cultivo-de-quinoa-en-una-region-andina-Foto-FAO-3-1024x464.jpg 1024w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Los-cultivos-locales-se-presentan-como-alternativas-a-las-transnacionales-de-alimentos-_-Cultivo-de-quinoa-en-una-region-andina-Foto-FAO-3-768x348.jpg 768w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Los-cultivos-locales-se-presentan-como-alternativas-a-las-transnacionales-de-alimentos-_-Cultivo-de-quinoa-en-una-region-andina-Foto-FAO-3.jpg 1170w\" sizes=\"auto, (max-width: 633px) 100vw, 633px\" \/><figcaption id=\"caption-attachment-48820\" class=\"wp-caption-text\">Los cultivos locales se presentan como alternativas a las transnacionales de alimentos _ Cultivo de quinoa en una regi\u00f3n andina. Foto FAO.<\/figcaption><\/figure>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En esa radiograf\u00eda mundial sobresale otro dato interesante: la agricultura org\u00e1nica es mucho m\u00e1s eficiente (a nivel de uso de energ\u00eda) que la industrial. En enero del 2021, el <em>International Journal of Agriculture Technology<\/em>\u00a0public\u00f3 un estudio sobre la producci\u00f3n de arroz en Filipinas. En este caso concreto, la agricultura org\u00e1nica result\u00f3 un 63% m\u00e1s eficiente, en t\u00e9rminos de empleo energ\u00e9tico, y con rendimientos similares.<\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El sistema alimentario europeo es igualmente dependiente de los combustibles f\u00f3siles. De ah\u00ed el impacto significativo de la guerra Rusia-Ucrania tanto en el suministro energ\u00e9tico como en el correspondiente incremento del precio de los comestibles, dado que un cuarto de toda la energ\u00eda que se consume en el continente se destina a ese sector.<\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Un problema subsidiario no menos central en esta coyuntura: para compensar la reducci\u00f3n significativa de la energ\u00eda que habitualmente importaba de Rusia, Europa se est\u00e1 abasteciendo en pa\u00edses de Asia. Por ejemplo, le compra carb\u00f3n a Indonesia y gas a Malasia, lo que repercute en un aumento de los costos que deben pagar las comunidades locales de esas naciones abastecedoras. As\u00ed mismo, comunidades de Pakist\u00e1n y Bangladesh est\u00e1n sufriendo cortes de gas debido a que buena parte de su producci\u00f3n se desv\u00eda hacia Europa.<\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Es conocido, tambi\u00e9n, el impacto directo de los conflictos b\u00e9licos (crisis militares) en el aumento de las condiciones de degradaci\u00f3n social. Seg\u00fan la ONG <a href=\"https:\/\/www.actioncontrelafaim.org\/a-la-une\/conflits-quels-impacts-sur-la-faim\/\"><i>Acci\u00f3n contra el hambre<\/i><\/a>, el 60% de las personas que padecen de ese flagelo viven en pa\u00edses en guerra .<\/span><\/p>\n<figure id=\"attachment_48813\" aria-describedby=\"caption-attachment-48813\" style=\"width: 555px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48813\" src=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Los-conflictos-belicos-conspiran-contra-la-estabilidad-planetaria-independientemente-del-continente-donde-se-produzcan-Foto-Ayuda-en-Accion-300x127.jpg\" alt=\"\" width=\"555\" height=\"235\" srcset=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Los-conflictos-belicos-conspiran-contra-la-estabilidad-planetaria-independientemente-del-continente-donde-se-produzcan-Foto-Ayuda-en-Accion-300x127.jpg 300w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Los-conflictos-belicos-conspiran-contra-la-estabilidad-planetaria-independientemente-del-continente-donde-se-produzcan-Foto-Ayuda-en-Accion-768x325.jpg 768w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Los-conflictos-belicos-conspiran-contra-la-estabilidad-planetaria-independientemente-del-continente-donde-se-produzcan-Foto-Ayuda-en-Accion.jpg 773w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><figcaption id=\"caption-attachment-48813\" class=\"wp-caption-text\">Los conflictos b\u00e9licos conspiran contra la estabilidad planetaria independientemente del continente dnde se produzcan. Foto Ayuda en Accion<\/figcaption><\/figure>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Toda esta situaci\u00f3n agrava la crisis ambiental en un planeta que se dirige a un aumento de su temperatura de 2,5\u00b0C para el a\u00f1o 2100. Una mayor producci\u00f3n de combustibles f\u00f3siles acelerar\u00e1 a\u00fan m\u00e1s la crisis clim\u00e1tica, la cual, a su vez, ejercer\u00e1 una mayor presi\u00f3n sobre la producci\u00f3n alimentaria global. El calentamiento excesivo ya est\u00e1 causando estragos en la producci\u00f3n de alimentos debido a sequ\u00edas, inundaciones, tormentas y temperaturas muy altas que hacen insoportable en ciertos momentos del a\u00f1o el trabajo rural a campo abierto.<\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><i>Grain<\/i> concluye afirmando que no se puede resolver la crisis energ\u00e9tica o la alimentaria con medidas que empeoren la crisis clim\u00e1tica: \u201cEstas tres crisis est\u00e1n estrechamente conectadas y se superponen\u201d. Encontrar una salida a esta \u201cpolicrisis\u201d, enfatiza <i>Grain<\/i>, requiere una profunda transformaci\u00f3n de la manera como se producen y distribuyen la energ\u00eda y los alimentos, con acciones que cuestionen frontalmente el control de las grandes transnacionales, principales responsables de este \u201cdesastre planetario\u201d. A nivel de argumento, la ONG recuerda el <i>tweet<\/i> de noviembre pasado de Robert Reich, ex secretario de Trabajo de los Estados Unidos: \u201c<i>Un mensaje a los medios: por favor no informen que la inflaci\u00f3n lleg\u00f3 a un m\u00e1ximo en 40 a\u00f1os sin mencionar tambi\u00e9n que las utilidades de las corporaciones llegaron a un m\u00e1ximo en 70 a\u00f1os. Hay que mostrar el panorama completo\u201d.<\/i><\/span><\/p>\n<h5 class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 18pt;\"><b>Voraces, como siempre<\/b><\/span><\/h5>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Las grandes transnacionales se aprovechan de la crisis, aumentan los precios de sus productos de forma desproporcionada, provocan-usufruct\u00faan el aumento inflacionario y obtienen m\u00e1rgenes de ganancias estratosf\u00e9ricos, afirma <i>Grain. <\/i><\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En el caso de los Estados Unidos, por ejemplo, los expertos constatan que mientras las utilidades corporativas explican el 11% del aumento de precios desde 1979 a 2019, de ning\u00fan modo pueden justificar el desmedido aumento actual de 53,9%. En particular, en el sector alimentario, incluyendo las cadenas de supermercados y restaurantes. En Canad\u00e1, el gobierno inici\u00f3 una investigaci\u00f3n oficial sobre esta explosi\u00f3n de ganancias, mientras que en Europa y Australia varios empresarios, as\u00ed como numerosos medios de comunicaci\u00f3n, reconocen que la reciente escalada de precios es injustificada.<\/span><\/p>\n<figure id=\"attachment_48811\" aria-describedby=\"caption-attachment-48811\" style=\"width: 556px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48811\" src=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/La-ley-del-mas-rico-_-Informe-2013-de-Oxfam-300x150.jpeg\" alt=\"\" width=\"556\" height=\"278\" srcset=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/La-ley-del-mas-rico-_-Informe-2013-de-Oxfam-300x150.jpeg 300w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/La-ley-del-mas-rico-_-Informe-2013-de-Oxfam-768x384.jpeg 768w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/La-ley-del-mas-rico-_-Informe-2013-de-Oxfam.jpeg 773w\" sizes=\"auto, (max-width: 556px) 100vw, 556px\" \/><figcaption id=\"caption-attachment-48811\" class=\"wp-caption-text\">La ley del m\u00e1s rico. Informe 2013 de Oxfam<\/figcaption><\/figure>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En su informe <i><a href=\"https:\/\/www.oxfam.org\/en\/research\/la-ley-delmas-rico\">La ley del m\u00e1s rico<\/a><\/i>, que Oxfam Internacional public\u00f3 a mitad de enero, simult\u00e1neamente con la apertura del Foro de Davos, dicha organizaci\u00f3n coincide con la descripci\u00f3n global de <i>Grain <\/i>de un panorama mundial desalentador y su conclusi\u00f3n de que \u201cel mundo est\u00e1 atravesando una \u00e9poca sin precedentes, marcada por la acumulaci\u00f3n de m\u00faltiples crisis\u201d. Y pone el cursor de su an\u00e1lisis en la problem\u00e1tica del hambre (\u00a0 ).<\/span><\/p>\n<h5 class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><b><span style=\"font-size: 18pt;\">Impuestos a las fortunas y redistribuci\u00f3n del ingreso<\/span><\/b><\/span><\/h5>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Oxfam sostiene que cientos de millones m\u00e1s afrontan aumentos insostenibles del costo de los productos b\u00e1sicos o de la energ\u00eda necesaria para calentar sus hogares. El colapso clim\u00e1tico est\u00e1 paralizando la econom\u00eda de algunas regiones, y fen\u00f3menos meteorol\u00f3gicos extremos obligan a much\u00edsima gente en todo el mundo a abandonar sus hogares. Recuerda, adem\u00e1s, que son millones los seres humanos que siguen sufriendo los corolarios de la pandemia del COVID-19, que ya se ha cobrado m\u00e1s de 20 millones de vidas. La pobreza se ha incrementado por primera vez en 25 a\u00f1os, subraya esta ONG internacional, mientras que los ultrarricos ven crecer dr\u00e1sticamente su riqueza y los beneficios empresariales alcanzan niveles r\u00e9cord, lo que hace que se dispare a\u00fan m\u00e1s la desigualdad social.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-48823 aligncenter\" src=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Un-mundo-fragmentado-300x225.jpg\" alt=\"\" width=\"416\" height=\"312\" srcset=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Un-mundo-fragmentado-300x225.jpg 300w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/Un-mundo-fragmentado.jpg 433w\" sizes=\"auto, (max-width: 416px) 100vw, 416px\" \/><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Los hechos hablan por s\u00ed mismos. Desde 2020, el 1% m\u00e1s rico ha acaparado casi dos terceras partes de la nueva riqueza generada en el mundo: casi el doble de lo que se distribuye entre el 99% restante.<\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Cada d\u00eda, la fortuna de los milmillonarios aumenta en 2.700 millones de d\u00f3lares, mientras que los salarios de unos 1.700 millones de trabajadoras y trabajadores crecen deficientemente, aun por debajo de lo que sube la inflaci\u00f3n.<\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En 2022, las empresas energ\u00e9ticas y de alimentaci\u00f3n duplicaron con creces sus beneficios y distribuyeron 257.000 millones de d\u00f3lares en dividendos a sus accionistas, mientras que m\u00e1s de 800 millones de personas padec\u00edan hambre.<\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Oxfam se\u00f1ala que, por cada d\u00f3lar recaudado en impuestos a nivel global, tan s\u00f3lo 4 centavos provienen de impuestos a la riqueza. Por otra parte, la mitad de los milmillonarios del mundo vive en pa\u00edses donde no se aplica ning\u00fan impuesto a la riqueza que heredan sus descendientes.<\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Oxfam propone un impuesto a la riqueza de hasta el 5% para los multimillonarios y milmillonarios. Esto permitir\u00eda recaudar anualmente 1,7 billones de d\u00f3lares, monto que asegurar\u00eda que 2.000 millones de personas salgan de la situaci\u00f3n de pobreza, adem\u00e1s de financiar un plan mundial para acabar con el hambre.<\/span><\/p>\n<p class=\"ydpdc81c5dayiv4181523493ydpdaed15a6MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><i>Grain,<\/i> que coincide con la propuesta de aplicar impuestos a las grandes fortunas, insiste en la necesidad de darle prioridad a la conservaci\u00f3n de la energ\u00eda. De igual manera, seguir estimulando la reducci\u00f3n del desecho de alimentos, que actualmente origina el 8% de las emisiones clim\u00e1ticas globales.\u00a0Y tambi\u00e9n disminuir el consumo donde tenga sentido (carne, l\u00e1cteos, comestibles ultra procesados) e invertir m\u00e1s en modelos alimentarios de base comunitaria. <i>Grain <\/i>propone, tambi\u00e9n, cerrar la industria de los combustibles f\u00f3siles y ganar el apoyo p\u00fablico para promover sistemas alimentarios colectivos y locales. \u201cEsto significa apoyar a quienes producen en peque\u00f1a escala y a los mercados locales, al mismo tiempo que se desmantela el poder y las ganancias de la cadena alimentaria corporativa\u201d, concluye<\/span><span style=\"font-size: 14pt;\">.<\/span><\/p>\n<figure id=\"attachment_48814\" aria-describedby=\"caption-attachment-48814\" style=\"width: 566px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48814\" src=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/La-produccion-local-es-una-premisa-para-la-soberania-alimentaria-Foto-Caritas-Internacional-300x169.jpeg\" alt=\"\" width=\"566\" height=\"319\" srcset=\"https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/La-produccion-local-es-una-premisa-para-la-soberania-alimentaria-Foto-Caritas-Internacional-300x169.jpeg 300w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/La-produccion-local-es-una-premisa-para-la-soberania-alimentaria-Foto-Caritas-Internacional-1024x576.jpeg 1024w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/La-produccion-local-es-una-premisa-para-la-soberania-alimentaria-Foto-Caritas-Internacional-768x432.jpeg 768w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/La-produccion-local-es-una-premisa-para-la-soberania-alimentaria-Foto-Caritas-Internacional-870x489.jpeg 870w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/La-produccion-local-es-una-premisa-para-la-soberania-alimentaria-Foto-Caritas-Internacional-895x503.jpeg 895w, https:\/\/www.lapluma.net\/wp-content\/uploads\/2023\/02\/La-produccion-local-es-una-premisa-para-la-soberania-alimentaria-Foto-Caritas-Internacional.jpeg 1500w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><figcaption id=\"caption-attachment-48814\" class=\"wp-caption-text\">La producci\u00f3n local es una premisa para la soberan\u00eda alimentaria. Foto Caritas Internacional<\/figcaption><\/figure>\n<h2><span style=\"font-size: 18pt;\">Sergio Ferrari <b>desde Berna, Suiza<\/b>, para La Pluma, 12 de febrero de 2023<\/span><\/h2>\n<h2><span style=\"font-size: 18pt;\">Editado por <a href=\"https:\/\/www.lapluma.net\/nosotros\/editora\/\">Mar\u00eda Piedad Ossaba<\/a><\/span><\/h2>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Acaba de realizarse otro Foro Econ\u00f3mico de Davos, con pura ret\u00f3rica y mucho de show medi\u00e1tico, pero sin propuestas concretas para resolver el desorden del actual sistema mundial, donde se entrelazan varias crisis en una. <\/p>\n","protected":false},"author":887,"featured_media":48827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[218],"tags":[22306,22305,22307,22308,7682],"coauthors":[13416],"class_list":["post-48808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monde","tag-cadtm-contracumbre-mundial-de-los-movimientos-sociales","tag-energia-alimentos-clima-y-guerras","tag-fondo-monetario-internacional-fmi-banco-mundial-bm-y-el-fmi","tag-policrisis","tag-sergio-ferrari"],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"fr","enabled_languages":["es","fr"],"languages":{"es":{"title":true,"content":true,"excerpt":true},"fr":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/posts\/48808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/users\/887"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/comments?post=48808"}],"version-history":[{"count":8,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/posts\/48808\/revisions"}],"predecessor-version":[{"id":48831,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/posts\/48808\/revisions\/48831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/media\/48827"}],"wp:attachment":[{"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/media?parent=48808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/categories?post=48808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/tags?post=48808"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.lapluma.net\/fr\/wp-json\/wp\/v2\/coauthors?post=48808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}